{"id":10118,"date":"2022-04-20T12:48:43","date_gmt":"2022-04-20T12:48:43","guid":{"rendered":"https:\/\/apartments.zeitraum.re\/room\/double-room-copy\/"},"modified":"2022-07-11T12:55:01","modified_gmt":"2022-07-11T12:55:01","slug":"double-room-karl","status":"publish","type":"room","link":"https:\/\/apartments.zeitraum.re\/cs\/room\/double-room-karl\/","title":{"rendered":"Apartm\u00e1n &#8211; Jeden pokoj"},"content":{"rendered":"<div class=\"s6 col ng-scope\">\n<p>Na\u0161e pln\u011b vybaven\u00e9 apartm\u00e1ny s jedn\u00edm pokojem maj\u00ed velkou postel, kuchy\u0148 s n\u00e1dob\u00edm a my\u010dkou, st\u016fl s posezen\u00edm, syst\u00e9m podlahov\u00e9ho vyt\u00e1p\u011bn\u00ed a smart televizi s plochou obrazovkou. V koupeln\u011b najdete sprchu, kosmetiku, f\u00e9n a ru\u010dn\u00edky. N\u011bkter\u00e9 z pokoj\u016f maj\u00ed vlastn\u00ed balkon. Wi-Fi je zdarma. Pokoj je vhodn\u00fd pro 2 osoby.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-10521 size-full\" src=\"https:\/\/apartments.zeitraum.re\/wp-content\/uploads\/2022\/04\/4-6.jpg\" alt=\"\" width=\"1024\" height=\"724\" srcset=\"https:\/\/apartments.zeitraum.re\/wp-content\/uploads\/2022\/04\/4-6.jpg 1024w, https:\/\/apartments.zeitraum.re\/wp-content\/uploads\/2022\/04\/4-6-300x212.jpg 300w, https:\/\/apartments.zeitraum.re\/wp-content\/uploads\/2022\/04\/4-6-768x543.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Na\u0161e pln\u011b vybaven\u00e9 apartm\u00e1ny s jedn\u00edm pokojem maj\u00ed velkou postel, kuchy\u0148 s n\u00e1dob\u00edm a my\u010dkou, st\u016fl s posezen\u00edm, syst\u00e9m podlahov\u00e9ho vyt\u00e1p\u011bn\u00ed a smart televizi s plochou obrazovkou. V koupeln\u011b najdete sprchu, kosmetiku, f\u00e9n a ru\u010dn\u00edky. N\u011bkter\u00e9 z pokoj\u016f maj\u00ed vlastn\u00ed balkon. Wi-Fi je zdarma. Pokoj je vhodn\u00fd pro 2 osoby.<\/p>\n","protected":false},"featured_media":10260,"menu_order":19,"template":"","acf":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.2.2 -->\r\n\t\t<title>Zeitraum Apartments | Apartm\u00e1ny k pron\u00e1jmu Praha 1<\/title>\n\t\t<meta name=\"description\" content=\"Stylov\u00e9 apartm\u00e1ny k pron\u00e1jmu v centru Prahy. Vhodn\u00e9 pro dovolenou, pracovn\u00ed pobyt i pron\u00e1jem. Kompletn\u00ed vybaven\u00ed, vlastn\u00ed kuchyn\u011b, WIFI, recepce.\" \/>\n\t\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t\t<link rel=\"canonical\" href=\"https:\/\/apartments.zeitraum.re\/cs\/room\/double-room-karl\/\" \/>\n\t\t<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n\t\t<meta property=\"og:site_name\" content=\"ZEITRAUM Apartments\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Zeitraum Apartments | Apartm\u00e1ny k pron\u00e1jmu Praha 1\" \/>\n\t\t<meta property=\"og:description\" content=\"Stylov\u00e9 apartm\u00e1ny k pron\u00e1jmu v centru Prahy. Vhodn\u00e9 pro dovolenou, pracovn\u00ed pobyt i pron\u00e1jem. Kompletn\u00ed vybaven\u00ed, vlastn\u00ed kuchyn\u011b, WIFI, recepce.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/apartments.zeitraum.re\/cs\/room\/double-room-karl\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/apartments.zeitraum.re\/wp-content\/uploads\/2022\/04\/photo-13.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/apartments.zeitraum.re\/wp-content\/uploads\/2022\/04\/photo-13.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-04-20T12:48:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-07-11T12:55:01+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZeitraumApartments\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Zeitraum Apartments | Apartm\u00e1ny k pron\u00e1jmu Praha 1\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Stylov\u00e9 apartm\u00e1ny k pron\u00e1jmu v centru Prahy. Vhodn\u00e9 pro dovolenou, pracovn\u00ed pobyt i pron\u00e1jem. Kompletn\u00ed vybaven\u00ed, vlastn\u00ed kuchyn\u011b, WIFI, recepce.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/apartments.zeitraum.re\/wp-content\/uploads\/2022\/04\/photo-13.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"sweb\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/#website\",\"url\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/\",\"name\":\"ZEITRAUM Apartments\",\"inLanguage\":\"cs-CZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/#organization\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/#organization\",\"name\":\"ZEITRAUM Apartments\",\"url\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/#organizationLogo\",\"url\":\"https:\\\/\\\/apartments.zeitraum.re\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/apartmetns_logo_color.jpg\",\"width\":2416,\"height\":716},\"image\":{\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZeitraumApartments\",\"https:\\\/\\\/www.instagram.com\\\/franzbyzeitraum\\\/\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"+420603951250\",\"contactType\":\"Customer Support\"}},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/room\\\/double-room-karl\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/#listItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/\",\"name\":\"Home\",\"description\":\"Stylov\\u00e9 apartm\\u00e1ny k pron\\u00e1jmu v centru Prahy a Plzn\\u011b. Vhodn\\u00e9 pro dovolenou, pracovn\\u00ed pobyt i pron\\u00e1jem. Kompletn\\u00ed vybaven\\u00ed, vlastn\\u00ed kuchyn\\u011b, WIFI, recepce.\",\"url\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/\"},\"nextItem\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/room\\\/double-room-karl\\\/#listItem\"},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/room\\\/double-room-karl\\\/#listItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/room\\\/double-room-karl\\\/\",\"name\":\"Apartm\\u00e1n - Jeden pokoj\",\"description\":\"Stylov\\u00e9 apartm\\u00e1ny k pron\\u00e1jmu v centru Prahy. Vhodn\\u00e9 pro dovolenou, pracovn\\u00ed pobyt i pron\\u00e1jem. Kompletn\\u00ed vybaven\\u00ed, vlastn\\u00ed kuchyn\\u011b, WIFI, recepce.\",\"url\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/room\\\/double-room-karl\\\/\"},\"previousItem\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/#listItem\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/author\\\/sweb\\\/#author\",\"url\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/author\\\/sweb\\\/\",\"name\":\"sweb\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/room\\\/double-room-karl\\\/#webpage\",\"url\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/room\\\/double-room-karl\\\/\",\"name\":\"Zeitraum Apartments | Apartm\\u00e1ny k pron\\u00e1jmu Praha 1\",\"description\":\"Stylov\\u00e9 apartm\\u00e1ny k pron\\u00e1jmu v centru Prahy. Vhodn\\u00e9 pro dovolenou, pracovn\\u00ed pobyt i pron\\u00e1jem. Kompletn\\u00ed vybaven\\u00ed, vlastn\\u00ed kuchyn\\u011b, WIFI, recepce.\",\"inLanguage\":\"cs-CZ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/room\\\/double-room-karl\\\/#breadcrumblist\"},\"author\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/author\\\/sweb\\\/#author\",\"creator\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/author\\\/sweb\\\/#author\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/#mainImage\",\"url\":\"https:\\\/\\\/apartments.zeitraum.re\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/photo-13.jpg\",\"width\":1920,\"height\":1280},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apartments.zeitraum.re\\\/cs\\\/room\\\/double-room-karl\\\/#mainImage\"},\"datePublished\":\"2022-04-20T12:48:43+00:00\",\"dateModified\":\"2022-07-11T12:55:01+00:00\"}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\n\n","aioseo_head_json":{"title":"Zeitraum Apartments | Apartm\u00e1ny k pron\u00e1jmu Praha 1","description":"Stylov\u00e9 apartm\u00e1ny k pron\u00e1jmu v centru Prahy. Vhodn\u00e9 pro dovolenou, pracovn\u00ed pobyt i pron\u00e1jem. Kompletn\u00ed vybaven\u00ed, vlastn\u00ed kuchyn\u011b, WIFI, recepce.","canonical_url":"https:\/\/apartments.zeitraum.re\/cs\/room\/double-room-karl\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"og:locale":"cs_CZ","og:site_name":"ZEITRAUM Apartments","og:type":"article","og:title":"Zeitraum Apartments | Apartm\u00e1ny k pron\u00e1jmu Praha 1","og:description":"Stylov\u00e9 apartm\u00e1ny k pron\u00e1jmu v centru Prahy. Vhodn\u00e9 pro dovolenou, pracovn\u00ed pobyt i pron\u00e1jem. Kompletn\u00ed vybaven\u00ed, vlastn\u00ed kuchyn\u011b, WIFI, recepce.","og:url":"https:\/\/apartments.zeitraum.re\/cs\/room\/double-room-karl\/","og:image":"https:\/\/apartments.zeitraum.re\/wp-content\/uploads\/2022\/04\/photo-13.jpg","og:image:secure_url":"https:\/\/apartments.zeitraum.re\/wp-content\/uploads\/2022\/04\/photo-13.jpg","og:image:width":"1920","og:image:height":"1280","article:published_time":"2022-04-20T12:48:43+00:00","article:modified_time":"2022-07-11T12:55:01+00:00","article:publisher":"https:\/\/www.facebook.com\/ZeitraumApartments","twitter:card":"summary_large_image","twitter:title":"Zeitraum Apartments | Apartm\u00e1ny k pron\u00e1jmu Praha 1","twitter:description":"Stylov\u00e9 apartm\u00e1ny k pron\u00e1jmu v centru Prahy. Vhodn\u00e9 pro dovolenou, pracovn\u00ed pobyt i pron\u00e1jem. Kompletn\u00ed vybaven\u00ed, vlastn\u00ed kuchyn\u011b, WIFI, recepce.","twitter:image":"https:\/\/apartments.zeitraum.re\/wp-content\/uploads\/2022\/04\/photo-13.jpg","twitter:label1":"Written by","twitter:data1":"sweb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/apartments.zeitraum.re\/cs\/#website","url":"https:\/\/apartments.zeitraum.re\/cs\/","name":"ZEITRAUM Apartments","inLanguage":"cs-CZ","publisher":{"@id":"https:\/\/apartments.zeitraum.re\/cs\/#organization"}},{"@type":"Organization","@id":"https:\/\/apartments.zeitraum.re\/cs\/#organization","name":"ZEITRAUM Apartments","url":"https:\/\/apartments.zeitraum.re\/cs\/","logo":{"@type":"ImageObject","@id":"https:\/\/apartments.zeitraum.re\/cs\/#organizationLogo","url":"https:\/\/apartments.zeitraum.re\/wp-content\/uploads\/2021\/04\/apartmetns_logo_color.jpg","width":2416,"height":716},"image":{"@id":"https:\/\/apartments.zeitraum.re\/cs\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/ZeitraumApartments","https:\/\/www.instagram.com\/franzbyzeitraum\/"],"contactPoint":{"@type":"ContactPoint","telephone":"+420603951250","contactType":"Customer Support"}},{"@type":"BreadcrumbList","@id":"https:\/\/apartments.zeitraum.re\/cs\/room\/double-room-karl\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/apartments.zeitraum.re\/cs\/#listItem","position":1,"item":{"@type":"WebPage","@id":"https:\/\/apartments.zeitraum.re\/cs\/","name":"Home","description":"Stylov\u00e9 apartm\u00e1ny k pron\u00e1jmu v centru Prahy a Plzn\u011b. Vhodn\u00e9 pro dovolenou, pracovn\u00ed pobyt i pron\u00e1jem. Kompletn\u00ed vybaven\u00ed, vlastn\u00ed kuchyn\u011b, WIFI, recepce.","url":"https:\/\/apartments.zeitraum.re\/cs\/"},"nextItem":"https:\/\/apartments.zeitraum.re\/cs\/room\/double-room-karl\/#listItem"},{"@type":"ListItem","@id":"https:\/\/apartments.zeitraum.re\/cs\/room\/double-room-karl\/#listItem","position":2,"item":{"@type":"WebPage","@id":"https:\/\/apartments.zeitraum.re\/cs\/room\/double-room-karl\/","name":"Apartm\u00e1n - Jeden pokoj","description":"Stylov\u00e9 apartm\u00e1ny k pron\u00e1jmu v centru Prahy. Vhodn\u00e9 pro dovolenou, pracovn\u00ed pobyt i pron\u00e1jem. Kompletn\u00ed vybaven\u00ed, vlastn\u00ed kuchyn\u011b, WIFI, recepce.","url":"https:\/\/apartments.zeitraum.re\/cs\/room\/double-room-karl\/"},"previousItem":"https:\/\/apartments.zeitraum.re\/cs\/#listItem"}]},{"@type":"Person","@id":"https:\/\/apartments.zeitraum.re\/cs\/author\/sweb\/#author","url":"https:\/\/apartments.zeitraum.re\/cs\/author\/sweb\/","name":"sweb"},{"@type":"WebPage","@id":"https:\/\/apartments.zeitraum.re\/cs\/room\/double-room-karl\/#webpage","url":"https:\/\/apartments.zeitraum.re\/cs\/room\/double-room-karl\/","name":"Zeitraum Apartments | Apartm\u00e1ny k pron\u00e1jmu Praha 1","description":"Stylov\u00e9 apartm\u00e1ny k pron\u00e1jmu v centru Prahy. Vhodn\u00e9 pro dovolenou, pracovn\u00ed pobyt i pron\u00e1jem. Kompletn\u00ed vybaven\u00ed, vlastn\u00ed kuchyn\u011b, WIFI, recepce.","inLanguage":"cs-CZ","isPartOf":{"@id":"https:\/\/apartments.zeitraum.re\/cs\/#website"},"breadcrumb":{"@id":"https:\/\/apartments.zeitraum.re\/cs\/room\/double-room-karl\/#breadcrumblist"},"author":"https:\/\/apartments.zeitraum.re\/cs\/author\/sweb\/#author","creator":"https:\/\/apartments.zeitraum.re\/cs\/author\/sweb\/#author","image":{"@type":"ImageObject","@id":"https:\/\/apartments.zeitraum.re\/cs\/#mainImage","url":"https:\/\/apartments.zeitraum.re\/wp-content\/uploads\/2022\/04\/photo-13.jpg","width":1920,"height":1280},"primaryImageOfPage":{"@id":"https:\/\/apartments.zeitraum.re\/cs\/room\/double-room-karl\/#mainImage"},"datePublished":"2022-04-20T12:48:43+00:00","dateModified":"2022-07-11T12:55:01+00:00"}]}},"aioseo_meta_data":{"post_id":"10118","title":"Zeitraum Apartments #separator_sa Apartm\u00e1ny k pron\u00e1jmu Praha 1","description":"Stylov\u00e9 apartm\u00e1ny k pron\u00e1jmu v centru Prahy. Vhodn\u00e9 pro dovolenou, pracovn\u00ed pobyt i pron\u00e1jem. Kompletn\u00ed vybaven\u00ed, vlastn\u00ed kuchyn\u011b, WIFI, recepce.","keywords":"[]","canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"featured","og_image_url":"https:\/\/apartments.zeitraum.re\/wp-content\/uploads\/2022\/04\/photo-13.jpg","og_image_width":"1920","og_image_height":"1280","og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":"[]","twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":"default","frequency":"default","local_seo":null,"limit_modified_date":false,"created":"2022-06-28 14:12:06","updated":"2022-07-11 13:06:23"},"_links":{"self":[{"href":"https:\/\/apartments.zeitraum.re\/cs\/wp-json\/wp\/v2\/room\/10118"}],"collection":[{"href":"https:\/\/apartments.zeitraum.re\/cs\/wp-json\/wp\/v2\/room"}],"about":[{"href":"https:\/\/apartments.zeitraum.re\/cs\/wp-json\/wp\/v2\/types\/room"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apartments.zeitraum.re\/cs\/wp-json\/wp\/v2\/media\/10260"}],"wp:attachment":[{"href":"https:\/\/apartments.zeitraum.re\/cs\/wp-json\/wp\/v2\/media?parent=10118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}